{"id":33288,"date":"2025-04-26T22:39:40","date_gmt":"2025-04-26T19:39:40","guid":{"rendered":"https:\/\/www.yachttogo.com\/?page_id=33288"},"modified":"2025-05-03T12:09:03","modified_gmt":"2025-05-03T09:09:03","slug":"forfait-de-location-de-bateau-tout-compris","status":"publish","type":"page","link":"https:\/\/www.yachttogo.com\/fr\/all-inclusive-yacht-charter-package\/","title":{"rendered":"Forfait de location de bateau tout compris"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-classic vc_cta3-shape-rounded vc_cta3-align-left vc_cta3-color-white vc_cta3-icon-size-md vc_cta3-actions-bottom vc_custom_1745693039736\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2>Yachts de luxe tout compris \u00e0 louer<\/h2><\/header><p>...<\/p>\n<h3><span style=\"color: #ff6600;\">Seuls 4 chalutiers de luxe peuvent b\u00e9n\u00e9ficier de cette campagne !<\/span><\/h3>\n<p>...<\/p>\n<\/div><div class=\"vc_cta3-actions\"><div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" ><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-modern vc_btn3-icon-left vc_btn3-color-primary\" href=\"tel:+905424841010\" title=\"+905424841010\" target=\"_blank\"><i class=\"vc_btn3-icon fas fa-phone-volume\"><\/i> Appelez-nous<\/a><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\"><h2 class=\"widgettitle\">Forfait de location de bateau tout compris<\/h2>\t\t\t<div class=\"textwidget\"><p>Avec notre formule de location de bateau tout compris, profitez de la plus grande libert\u00e9.<\/p>\n<p>Une fois que tout a \u00e9t\u00e9 pris en charge, mettez les voiles vers des destinations \u00e9tonnantes. Savourez le luxe, vivez l'aventure et cr\u00e9ez des souvenirs inoubliables.<\/p>\n<h3>Trouvez votre yacht id\u00e9al<\/h3>\n<p>Que comprennent les vacances tout compris ?<br \/>\nVotre choix de yacht de luxe<\/p>\n<p>Choisissez parmi notre magnifique flotte de yachts modernes et parfaitement entretenus, chacun d'entre eux \u00e9tant pr\u00e9cis\u00e9ment dimensionn\u00e9 pour r\u00e9pondre aux besoins et aux go\u00fbts de votre groupe.<\/p>\n<h3>\u00c9quipe d'experts<\/h3>\n<p>Savourez les connaissances de notre capitaine chevronn\u00e9, de notre chef talentueux et de notre \u00e9quipage vigilant, qui veilleront \u00e0 ce que votre voyage se d\u00e9roule sans encombre et avec un r\u00e9el plaisir.<\/p>\n<h3>Produits alimentaires et boissons<\/h3>\n<p>Savourez de d\u00e9licieux repas fra\u00eechement pr\u00e9par\u00e9s et un assortiment de boissons soigneusement choisies en fonction de vos pr\u00e9f\u00e9rences et de vos besoins alimentaires.<\/p>\n<h3>Activit\u00e9s et sports nautiques amusants<\/h3>\n<p>Acc\u00e9dez \u00e0 une vari\u00e9t\u00e9 d'\u00e9quipements de sports nautiques exaltants, tels que des planches \u00e0 pagaie et du mat\u00e9riel de plong\u00e9e avec tuba (la disponibilit\u00e9 peut varier selon le navire), et plongez dans l'aventure.<\/p>\n<p>Itin\u00e9raires s\u00e9lectionn\u00e9s<\/p>\n<p>Gr\u00e2ce \u00e0 nos itin\u00e9raires soigneusement \u00e9tudi\u00e9s, vous pourrez visiter des \u00eeles color\u00e9es, explorer des plages \u00e0 couper le souffle et d\u00e9couvrir des criques secr\u00e8tes. Vous pouvez m\u00eame cr\u00e9er votre propre exp\u00e9rience.<\/p>\n<p>Pas de frais inattendus, juste des loisirs<\/p>\n<p>Vous pouvez vous d\u00e9tendre en sachant que notre formule tout compris s'occupe de tout, ce qui vous permet de vous concentrer enti\u00e8rement sur la cr\u00e9ation de souvenirs inoubliables.<\/p>\n<h3>\u00cates-vous pr\u00eat \u00e0 partir ?<\/h3>\n<p>Il vous suffit de cliquer quelques fois pour vivre une exp\u00e9rience inoubliable. Faites-nous part de votre escapade id\u00e9ale, et ensemble, transformons-la en r\u00e9alit\u00e9 !<\/p>\n<p><a href=\"tel:+905424841010\">Obtenez votre devis personnalis\u00e9<\/a><\/p>\n<h3>D\u00e9couvrez des lieux \u00e9tonnants avec YachttoGO<\/h3>\n<p>Imaginez que vous d\u00e9couvriez des ports pittoresques et que vous vous r\u00e9veilliez devant des eaux bleues \u00e9poustouflantes. Nos forfaits tout compris proposent des voyages incroyables dans certains des endroits les plus populaires de la plan\u00e8te, tels que :<\/p>\n<p>Le littoral captivant de la Turquie<br \/>\nLes magnifiques \u00eeles grecques<br \/>\nLe magnifique littoral croate et de nombreux autres sites \u00e0 couper le souffle ne demandent qu'\u00e0 \u00eatre explor\u00e9s !<\/p>\n<p>Permettez-nous de vous aider \u00e0 s\u00e9lectionner l'endroit id\u00e9al qui servira de cadre \u00e0 votre excursion de r\u00eave.<\/p>\n<h3>Pourquoi choisir YachttoGO pour votre location de bateau tout compris ?<\/h3>\n<p>Une \u00e9l\u00e9gance in\u00e9gal\u00e9e : Profitez de la meilleure gamme de yachts et d'un service d\u00e9vou\u00e9 de premi\u00e8re qualit\u00e9.<br \/>\nUne planification sans stress : De l'\u00e9laboration d'un programme id\u00e9al \u00e0 la fourniture d'une cuisine raffin\u00e9e, nous nous occupons de tous les aspects.<br \/>\nExpertise : Profitez de la richesse de nos connaissances et de notre enthousiasme pour concevoir des locations de yachts exceptionnelles.<br \/>\nUn service sur mesure : Votre sp\u00e9cialiste de l'affr\u00e8tement est l\u00e0 pour s'assurer que tous vos besoins sont satisfaits.<br \/>\nNous nous engageons \u00e0 vous aider \u00e0 cr\u00e9er des souvenirs qui resteront longtemps grav\u00e9s dans votre m\u00e9moire.<\/p>\n<\/div>\n\t\t<\/div><\/div><section class=\"vc_cta3-container\"><div class=\"vc_general vc_do_cta3 vc_cta3 vc_cta3-style-classic vc_cta3-shape-rounded vc_cta3-align-center vc_cta3-color-turquoise vc_cta3-icon-size-md vc_cta3-actions-bottom vc_custom_1745693871933\"><div class=\"vc_cta3_content-container\"><div class=\"vc_cta3-content\"><header class=\"vc_cta3-content-header\"><h2>Ne manquez pas l'offre de mai ! - Location de bateau tout compris<\/h2><\/header><\/div><div class=\"vc_cta3-actions\"><div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" ><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-modern vc_btn3-block vc_btn3-icon-left vc_btn3-color-primary\" href=\"tel:+905424841010\" title=\"+905424841010\" target=\"_blank\"><i class=\"vc_btn3-icon fas fa-phone-volume\"><\/i> Appelez-nous<\/a><\/div><\/div><\/div><\/div><\/section><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div class=\"homey-module module-title section-title-module text-center\">\r\n\t\t\t<h2 >Yachts \u00e0 moteur tout compris \u00e0 louer \u00e0 Gocek, Fethiye, Turquie<\/h2>\r\n\r\n\t\t\t<p  class=\"sub-heading\">4 Trawlers pour une location de bateau tout compris<\/p>\r\n\t\t<\/div>\r\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n        <div class=\"module-wrap property-module-by-id property-module-by-id-2cols\">\n            <div class=\"listing-wrap which-layout-grid  item-grid-view\">\n                    <div class=\"col-sm-6\">\n<div class=\"item-wrap infobox_trigger homey-matchHeight item-grid-view infobox_trigger homey-matchHeight\" data-dir=\"listing-item\" data-id=\"33075\">\n    <div class=\"media property-item\">\n        <div class=\"media-left\">\n            <div class=\"item-media item-media-thumb\">\n                                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/by-cf-23m-luxury-trawler-4-cabins-sleeps-9\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Le luxueux chalutier BY CF de 23 m\u00e8tres navigue sur la Riviera turque\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-16x12.jpg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                                    <div class=\"item-media-price\">\n                        <span class=\"item-price\">\n                            2,600<sup>\u20ac<\/sup><sub>\/Nuit<\/sub>\n                        <\/span>\n                    <\/div>\n                \n                                    <div class=\"item-user-image\">\n                        <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <\/div>\n                            <\/div>\n        <\/div>\n        <div class=\"media-body item-body clearfix\">\n\n            <div class=\"item-title-head table-block\">\n                <div class=\"title-head-left\">\n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/by-cf-23m-luxury-trawler-4-cabins-sleeps-9\/\">\n                            BY CF : Trawler de luxe de 23m - 4 cabines, 9 couchages<\/a><\/h2>\n\n                    <address class=\"item-address\">Turquie, Gocek, Fethiye<\/address>        \n                <\/div>\n            <\/div>\n\n                        <ul class=\"item-amenities\">\n\n                                <li>\n                    <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i> \n                    <span class=\"total-beds\">4<\/span> <span class=\"item-label\">Cabines<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i> \n                    <span class=\"total-baths\">4<\/span> <span class=\"item-label\">Bains<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i> \n                    <span class=\"total-guests\">9<\/span> <span class=\"item-label\">Passagers<\/span>\n                <\/li>\n                \n                                <li class=\"item-type\">Chalutier<\/li>\n                            <\/ul>\n            \n                            <div class=\"item-user-image list-item-hidden\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <span class=\"item-user-info\">Accueillie par<br>\n                    Fatih Tok<\/span>\n                <\/div>\n            \n            <div class=\"item-footer\">\n\n                                    <div class=\"footer-right\">\n                        <div class=\"item-tools\">\n                            <div class=\"btn-group dropup\">\n                                <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33075\" data-listing_id=\"33075\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Comparer        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33075\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Ajouter aux favoris        <\/button>\n    <\/li>\n<\/ul>                            <\/div>\n                        <\/div>\n                    <\/div>\n                \n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div><!-- .item-wrap --><\/div><div class=\"col-sm-6\">\n<div class=\"item-wrap infobox_trigger homey-matchHeight item-grid-view infobox_trigger homey-matchHeight\" data-dir=\"listing-item\" data-id=\"31666\">\n    <div class=\"media property-item\">\n        <div class=\"media-left\">\n            <div class=\"item-media item-media-thumb\">\n                                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/oggusto\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-1024x683.jpg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-749x500.jpg 749w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-600x400.jpg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14-150x100.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/oggusto-trawler-14.jpg 1280w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                                    <div class=\"item-media-price\">\n                        <span class=\"item-price\">\n                            1,650<sup>\u20ac<\/sup><sub>\/jour<\/sub>\n                        <\/span>\n                    <\/div>\n                \n                                    <div class=\"item-user-image\">\n                        <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <\/div>\n                            <\/div>\n        <\/div>\n        <div class=\"media-body item-body clearfix\">\n\n            <div class=\"item-title-head table-block\">\n                <div class=\"title-head-left\">\n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/oggusto\/\">\n                            Oggusto<\/a><\/h2>\n\n                    <address class=\"item-address\">Turquie, Gocek, Fethiye<\/address>        \n                <\/div>\n            <\/div>\n\n                        <ul class=\"item-amenities\">\n\n                                <li>\n                    <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i> \n                    <span class=\"total-beds\">4<\/span> <span class=\"item-label\">Cabines<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i> \n                    <span class=\"total-baths\">4<\/span> <span class=\"item-label\">Bains<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i> \n                    <span class=\"total-guests\">8<\/span> <span class=\"item-label\">Passagers<\/span>\n                <\/li>\n                \n                                <li class=\"item-type\">Chalutier<\/li>\n                            <\/ul>\n            \n                            <div class=\"item-user-image list-item-hidden\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <span class=\"item-user-info\">Accueillie par<br>\n                    Fatih Tok<\/span>\n                <\/div>\n            \n            <div class=\"item-footer\">\n\n                                    <div class=\"footer-right\">\n                        <div class=\"item-tools\">\n                            <div class=\"btn-group dropup\">\n                                <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-31666\" data-listing_id=\"31666\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Comparer        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"31666\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Ajouter aux favoris        <\/button>\n    <\/li>\n<\/ul>                            <\/div>\n                        <\/div>\n                    <\/div>\n                \n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div><!-- .item-wrap --><\/div><div class=\"col-sm-6\">\n<div class=\"item-wrap infobox_trigger homey-matchHeight item-grid-view infobox_trigger homey-matchHeight\" data-dir=\"listing-item\" data-id=\"11182\">\n    <div class=\"media property-item\">\n        <div class=\"media-left\">\n            <div class=\"item-media item-media-thumb\">\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">En vedette<\/span>\n                <\/span>                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/trawler-simay-m-5-cabin-10-pax-trawler-for-charter-fethiye-gocek\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/08\/Trawler-Simay-M-\u2013-5-Cabin-10-Pax-Trawler-for-Charter-\u2013-Fethiye-Gocek-4-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/08\/Trawler-Simay-M-\u2013-5-Cabin-10-Pax-Trawler-for-Charter-\u2013-Fethiye-Gocek-4-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/08\/Trawler-Simay-M-\u2013-5-Cabin-10-Pax-Trawler-for-Charter-\u2013-Fethiye-Gocek-4-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/08\/Trawler-Simay-M-\u2013-5-Cabin-10-Pax-Trawler-for-Charter-\u2013-Fethiye-Gocek-4-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                                    <div class=\"item-media-price\">\n                        <span class=\"item-price\">\n                            2,000<sup>\u20ac<\/sup><sub>\/jour<\/sub>\n                        <\/span>\n                    <\/div>\n                \n                                    <div class=\"item-user-image\">\n                        <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <\/div>\n                            <\/div>\n        <\/div>\n        <div class=\"media-body item-body clearfix\">\n\n            <div class=\"item-title-head table-block\">\n                <div class=\"title-head-left\">\n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/trawler-simay-m-5-cabin-10-pax-trawler-for-charter-fethiye-gocek\/\">\n                            Trawler Simay M : 5 Cabines 10 Pax Trawler pour Charter Fethiye, G\u00f6cek<\/a><\/h2>\n\n                    <address class=\"item-address\">Turquie, Fethiye, Bodrum<\/address>        \n                <\/div>\n            <\/div>\n\n                        <ul class=\"item-amenities\">\n\n                                <li>\n                    <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i> \n                    <span class=\"total-beds\">5<\/span> <span class=\"item-label\">Cabines<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i> \n                    <span class=\"total-baths\">5<\/span> <span class=\"item-label\">Bains<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i> \n                    <span class=\"total-guests\">10<\/span> <span class=\"item-label\">Passagers<\/span>\n                <\/li>\n                \n                                <li class=\"item-type\">Chalutier<\/li>\n                            <\/ul>\n            \n                            <div class=\"item-user-image list-item-hidden\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <span class=\"item-user-info\">Accueillie par<br>\n                    Fatih Tok<\/span>\n                <\/div>\n            \n            <div class=\"item-footer\">\n\n                                    <div class=\"footer-right\">\n                        <div class=\"item-tools\">\n                            <div class=\"btn-group dropup\">\n                                <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-11182\" data-listing_id=\"11182\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Comparer        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"11182\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Ajouter aux favoris        <\/button>\n    <\/li>\n<\/ul>                            <\/div>\n                        <\/div>\n                    <\/div>\n                \n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div><!-- .item-wrap --><\/div><div class=\"col-sm-6\">\n<div class=\"item-wrap infobox_trigger homey-matchHeight item-grid-view infobox_trigger homey-matchHeight\" data-dir=\"listing-item\" data-id=\"5760\">\n    <div class=\"media property-item\">\n        <div class=\"media-left\">\n            <div class=\"item-media item-media-thumb\">\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">En vedette<\/span>\n                <\/span>                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/5-cabins-10-pax-luxury-trawler-motor-yacht-for-rent\/\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/simay-s-trawler-yacht-charter-1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/simay-s-trawler-yacht-charter-1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/simay-s-trawler-yacht-charter-1-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                                    <div class=\"item-media-price\">\n                        <span class=\"item-price\">\n                            2,000<sup>\u20ac<\/sup><sub>\/Nuit<\/sub>\n                        <\/span>\n                    <\/div>\n                \n                                    <div class=\"item-user-image\">\n                        <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <\/div>\n                            <\/div>\n        <\/div>\n        <div class=\"media-body item-body clearfix\">\n\n            <div class=\"item-title-head table-block\">\n                <div class=\"title-head-left\">\n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/fr\/rental-boat-yacht\/5-cabins-10-pax-luxury-trawler-motor-yacht-for-rent\/\">\n                            Simay S : 5 Cabines 10 Pax Luxury Trawler Motor Yacht Charter Turkey Fethiye<\/a><\/h2>\n\n                    <address class=\"item-address\">Turquie, Gr\u00e8ce, Fethiye, Bodrum<\/address>        \n                <\/div>\n            <\/div>\n\n                        <ul class=\"item-amenities\">\n\n                                <li>\n                    <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i> \n                    <span class=\"total-beds\">5<\/span> <span class=\"item-label\">Cabines<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i> \n                    <span class=\"total-baths\">5<\/span> <span class=\"item-label\">Bains<\/span>\n                <\/li>\n                \n                                <li>\n                    <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i> \n                    <span class=\"total-guests\">10<\/span> <span class=\"item-label\">Passagers<\/span>\n                <\/li>\n                \n                                <li class=\"item-type\">Chalutier<\/li>\n                            <\/ul>\n            \n                            <div class=\"item-user-image list-item-hidden\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                    <span class=\"item-user-info\">Accueillie par<br>\n                    Fatih Tok<\/span>\n                <\/div>\n            \n            <div class=\"item-footer\">\n\n                                    <div class=\"footer-right\">\n                        <div class=\"item-tools\">\n                            <div class=\"btn-group dropup\">\n                                <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-5760\" data-listing_id=\"5760\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Comparer        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"5760\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Ajouter aux favoris        <\/button>\n    <\/li>\n<\/ul>                            <\/div>\n                        <\/div>\n                    <\/div>\n                \n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div><!-- .item-wrap --><\/div>            <\/div><!-- grid-listing-page -->\n        <\/div>\n\n        <\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Simay S: 5 Cabins, 10 Pax Luxury Trawler Motor Yacht Charter Turkey &amp; Greece Simay S: 5 Cabins, 10 Pax Luxury Trawler Motor Yacht Charter Turkey Fethiye, &amp; Greece offers an extraordinary experience and stands out with its luxury. It was manufactured in Fethiye by Hasmarine Yachting in 2015 and was completely renovated in 2023. [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-33288","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/pages\/33288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/comments?post=33288"}],"version-history":[{"count":5,"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/pages\/33288\/revisions"}],"predecessor-version":[{"id":33464,"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/pages\/33288\/revisions\/33464"}],"wp:attachment":[{"href":"https:\/\/www.yachttogo.com\/fr\/wp-json\/wp\/v2\/media?parent=33288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}