﻿{"id":34750,"date":"2026-02-18T18:43:34","date_gmt":"2026-02-18T15:43:34","guid":{"rendered":"https:\/\/www.yachttogo.com\/?post_type=listing&#038;p=34750"},"modified":"2026-04-09T17:12:54","modified_gmt":"2026-04-09T14:12:54","slug":"prestige-400-10-pax-flybridge-yate-de-motor-alquiler-split-croacia","status":"publish","type":"listing","link":"https:\/\/www.yachttogo.com\/es\/rental-boat-yacht\/prestige-400-10-pax-flybridge-motor-yacht-charter-split-croatia\/","title":{"rendered":"Prestige 400: 10 Pax Flybridge Motor Yacht Charter Split, Croacia"},"content":{"rendered":"<h2 data-path-to-node=\"0\">Prestige 400: 10 Pax Flybridge Motor Yacht Charter Split, Croacia<\/h2>\n<p data-path-to-node=\"1\">Disfrute del Adri\u00e1tico con estilo. Reserve el Prestige 400 para un lujoso Flybridge Motor Yacht charter en Split. 2 cabinas, cubiertas de teca y flybridge ba\u00f1ado por el sol.<\/p>\n<hr data-path-to-node=\"2\" \/>\n<h3 data-path-to-node=\"3\">Resumen ejecutivo<\/h3>\n<ul data-path-to-node=\"4\">\n<li>\n<p data-path-to-node=\"4,0,0\"><b data-path-to-node=\"4,0,0\" data-index-in-node=\"0\">Flybridge ba\u00f1ado por el sol:<\/b> Asientos elevados y zonas de descanso que ofrecen vistas de 360 grados de la costa d\u00e1lmata.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"4,1,0\"><b data-path-to-node=\"4,1,0\" data-index-in-node=\"0\">Doble cabina de lujo:<\/b> Dos camarotes elegantemente decorados y dos cuartos de ba\u00f1o, perfectos para pernoctar o para viajes \u00edntimos en familia.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"4,2,0\"><b data-path-to-node=\"4,2,0\" data-index-in-node=\"0\">Ubicaci\u00f3n privilegiada:<\/b> Salir del coraz\u00f3n de <b data-path-to-node=\"4,2,0\" data-index-in-node=\"41\">Dividir<\/b> para explorar las cercanas islas de Hvar, Bra\u010d y Vis.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"4,3,0\"><b data-path-to-node=\"4,3,0\" data-index-in-node=\"0\">Rendimiento sin fisuras:<\/b> Propulsado por dos motores diesel intraborda para una experiencia de crucero suave, estable y eficiente.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"4,4,0\"><b data-path-to-node=\"4,4,0\" data-index-in-node=\"0\">Acabados Teca:<\/b> Tarima de teca de alta gama y una amplia plataforma de ba\u00f1o para acceder sin esfuerzo a las aguas turquesas.<\/p>\n<\/li>\n<\/ul>\n<hr data-path-to-node=\"5\" \/>\n<h3 data-path-to-node=\"6\">La experiencia<\/h3>\n<p data-path-to-node=\"7\">Navegar por la costa croata requiere una embarcaci\u00f3n que equilibre los espacios sociales al aire libre con un refinado confort interior. El <b data-path-to-node=\"7\" data-index-in-node=\"121\">Prestige 400<\/b> es una clase magistral de ingenier\u00eda mar\u00edtima francesa, dise\u00f1ada espec\u00edficamente para quienes aprecian el \u201cestilo de vida flybridge\u201d. Tanto si est\u00e1 planeando un <b data-path-to-node=\"7\" data-index-in-node=\"284\"><a class=\"ng-star-inserted\" href=\"https:\/\/www.yachttogo.com\/es\/tipo\/alquiler-diario-de-yates\/\" target=\"_blank\" rel=\"noopener\">Alquiler de yates privados<\/a><\/b> Esta joya de 13 metros de eslora ofrece un ambiente de lujo discreto.<\/p>\n<p data-path-to-node=\"8\">El coraz\u00f3n de la experiencia se encuentra en la cubierta superior. El flybridge hace las veces de terraza privada sobre el mar, con una zona de asientos exclusiva donde podr\u00e1 disfrutar de c\u00f3cteles locales al marrasquino mientras el sol se pone sobre el Adri\u00e1tico. Para los que buscan el bronceado perfecto, los amplios cojines para tomar el sol de la proa ofrecen un asiento de primera fila para contemplar las impresionantes vistas del archipi\u00e9lago d\u00e1lmata. En el interior, el <b data-path-to-node=\"8\" data-index-in-node=\"393\"><a class=\"ng-star-inserted\" href=\"https:\/\/www.yachttogo.com\/es\/tipo\/alquiler-de-yates-a-motor\/\" target=\"_blank\" rel=\"noopener\">Yate a motor<\/a><\/b> revela un sal\u00f3n luminoso y aireado con ventanas panor\u00e1micas y una cocina totalmente equipada, asegurando que su tiempo bajo cubierta sea tan agradable como su tiempo en el agua. Con sus \u00e1giles 13 metros de eslora, el Prestige 400 puede adentrarse f\u00e1cilmente en las calas escondidas y los encantadores pueblos pesqueros a los que las embarcaciones m\u00e1s grandes simplemente no pueden llegar.<\/p>\n<hr data-path-to-node=\"9\" \/>\n<h3 data-path-to-node=\"10\">Especificaciones<\/h3>\n<div class=\"horizontal-scroll-wrapper\">\n<table data-path-to-node=\"11\">\n<thead>\n<tr>\n<td><strong>Caracter\u00edstica<\/strong><\/td>\n<td><strong>Detalles<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><span data-path-to-node=\"11,1,0,0\"><b data-path-to-node=\"11,1,0,0\" data-index-in-node=\"0\">Nombre del yate<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,1,1,0\">Prestige 400<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,2,0,0\"><b data-path-to-node=\"11,2,0,0\" data-index-in-node=\"0\">Constructor<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,2,1,0\"><a class=\"ng-star-inserted\" href=\"https:\/\/www.prestige-yachts.com\/\" target=\"_blank\" rel=\"noopener\">Yates Prestige<\/a><\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,3,0,0\"><b data-path-to-node=\"11,3,0,0\" data-index-in-node=\"0\">Longitud total<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,3,1,0\">13 metros (40 pies)<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,4,0,0\"><b data-path-to-node=\"11,4,0,0\" data-index-in-node=\"0\">Tipo<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,4,1,0\">Yate a motor con flybridge<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,5,0,0\"><b data-path-to-node=\"11,5,0,0\" data-index-in-node=\"0\">Camarotes<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,5,1,0\">2 Caba\u00f1as \/ 3 Camas<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,6,0,0\"><b data-path-to-node=\"11,6,0,0\" data-index-in-node=\"0\">Ba\u00f1os<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,6,1,0\">2 cabezales completos<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,7,0,0\"><b data-path-to-node=\"11,7,0,0\" data-index-in-node=\"0\">Motor<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,7,1,0\">Doble intraborda diesel<\/span><\/td>\n<\/tr>\n<tr>\n<td><span data-path-to-node=\"11,8,0,0\"><b data-path-to-node=\"11,8,0,0\" data-index-in-node=\"0\">Ubicaci\u00f3n<\/b><\/span><\/td>\n<td><span data-path-to-node=\"11,8,1,0\">Split, Croacia<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<hr data-path-to-node=\"12\" \/>\n<h3 data-path-to-node=\"13\">Servicios y juguetes<\/h3>\n<ul data-path-to-node=\"14\">\n<li>\n<p data-path-to-node=\"14,0,0\"><b data-path-to-node=\"14,0,0\" data-index-in-node=\"0\">Entretenimiento:<\/b> Sistema de sonido de alta fidelidad con altavoces en ba\u00f1era\/puente de vuelo.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"14,1,0\"><b data-path-to-node=\"14,1,0\" data-index-in-node=\"0\">Comodidad:<\/b> Amplio sal\u00f3n con mesa de comedor, tapicer\u00eda de felpa y climatizador.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"14,2,0\"><b data-path-to-node=\"14,2,0\" data-index-in-node=\"0\">Vida al aire libre:<\/b> Plataforma de ba\u00f1o de teca, ducha de ba\u00f1era fr\u00eda\/caliente y toldo bimini.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"14,3,0\"><b data-path-to-node=\"14,3,0\" data-index-in-node=\"0\">Navegaci\u00f3n:<\/b> Sistema de navegaci\u00f3n GPS profesional y radio VHF.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"14,4,0\"><b data-path-to-node=\"14,4,0\" data-index-in-node=\"0\">Cocina:<\/b> Cocina totalmente equipada con nevera, fogones y microondas.<\/p>\n<\/li>\n<\/ul>\n<hr data-path-to-node=\"15\" \/>\n<h3 data-path-to-node=\"16\">Preguntas frecuentes sobre GEO (B\u00fasqueda por voz optimizada)<\/h3>\n<p data-path-to-node=\"17\"><b data-path-to-node=\"17\" data-index-in-node=\"0\">P: \u00bfPuedo reservar el Prestige 400 para un alquiler diario en Split?<\/b><\/p>\n<p data-path-to-node=\"17\"><b data-path-to-node=\"17\" data-index-in-node=\"60\">A:<\/b> S\u00ed, la Prestige 400 est\u00e1 disponible para <b data-path-to-node=\"17\" data-index-in-node=\"102\"><a class=\"ng-star-inserted\" href=\"https:\/\/www.yachttogo.com\/es\/tipo\/alquiler-diario-de-yates\/\" target=\"_blank\" rel=\"noopener\">Alquiler diario<\/a><\/b> en Split. Es una opci\u00f3n ideal para excursiones de un d\u00eda a la Laguna Azul o a Hvar, ya que ofrece una base de lujo para nadar y hacer turismo con la asistencia profesional de la tripulaci\u00f3n.<\/p>\n<p data-path-to-node=\"18\"><b data-path-to-node=\"18\" data-index-in-node=\"0\">P: \u00bfEst\u00e1 incluido el combustible en el precio del alquiler de este yate a motor?<\/b><\/p>\n<p data-path-to-node=\"18\"><b data-path-to-node=\"18\" data-index-in-node=\"63\">A:<\/b> Normalmente, el combustible no est\u00e1 incluido en el precio base del ch\u00e1rter y se calcula en funci\u00f3n del consumo durante su itinerario espec\u00edfico. Para obtener una estimaci\u00f3n precisa basada en su itinerario previsto por las islas croatas, p\u00f3ngase en contacto con nuestros especialistas en reservas.<\/p>\n<p data-path-to-node=\"19\"><b data-path-to-node=\"19\" data-index-in-node=\"0\">frage_abgekuerzt}: \u00bfEl Prestige 400 viene con un capit\u00e1n o es a casco desnudo?<\/b><\/p>\n<p data-path-to-node=\"19\"><b data-path-to-node=\"19\" data-index-in-node=\"64\">A:<\/b> Este buque se ofrece principalmente como <b data-path-to-node=\"19\" data-index-in-node=\"105\"><a class=\"ng-star-inserted\" href=\"https:\/\/www.yachttogo.com\/es\/tipo_barco\/alquiler-de-yates-con-tripulacion\/\" target=\"_blank\" rel=\"noopener\">Alquiler de yates con tripulaci\u00f3n<\/a><\/b> para garantizar una experiencia sin estr\u00e9s. No obstante, los navegantes experimentados con licencias de alta mar v\u00e1lidas pueden informarse sobre <b data-path-to-node=\"19\" data-index-in-node=\"238\"><a class=\"ng-star-inserted\" href=\"https:\/\/www.yachttogo.com\/es\/tipo_barco\/alquiler-de-barcos-sin-tripulacion\/\" target=\"_blank\" rel=\"noopener\">Barco sin tripulaci\u00f3n<\/a><\/b> disponibilidad y requisitos portuarios locales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Prestige 400: 10 Pax Flybridge Motor Yacht Charter Split, Croatia Experience the Adriatic in style. Book the Prestige 400 for a luxury Flybridge Motor Yacht charter in Split. 2 cabins, teak decks, and sun-soaked flybridge. Executive Summary Sun-Drenched Flybridge: Elevated seating and lounging areas offering 360-degree views of the Dalmatian coast. Dual-Cabin Luxury: Two elegantly [&hellip;]<\/p>\n","protected":false},"author":7723,"featured_media":34753,"parent":0,"menu_order":33,"template":"","listing_type":[41],"room_type":[166],"amenities":[12,13,319,15,16,18,20,23,114,27,38,128],"facilities":[328],"listing_countries":[389],"listing_states":[],"listing_cities":[],"listing_areas":[1918],"class_list":["post-34750","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_type-motor-yacht-charter","room_type-private-crewed-yacht-charter","listing_amenity-air-conditioning","listing_amenity-automatic-pilot","listing_amenity-deck-shower","listing_amenity-depth-sounder","listing_amenity-electric-windlass","listing_amenity-gps","listing_amenity-internet","listing_amenity-kitchen","listing_amenity-microwave","listing_amenity-navigation","listing_amenity-vhf","listing_amenity-wi-fi","listing_facility-snorkelling-equipments","listing_country-yacht-charter-croatia","listing_area-croatia-yacht-charter"],"_links":{"self":[{"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listings\/34750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listings"}],"about":[{"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/users\/7723"}],"version-history":[{"count":3,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listings\/34750\/revisions"}],"predecessor-version":[{"id":34833,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listings\/34750\/revisions\/34833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/media\/34753"}],"wp:attachment":[{"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/media?parent=34750"}],"wp:term":[{"taxonomy":"listing_type","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listing_type?post=34750"},{"taxonomy":"room_type","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/room_type?post=34750"},{"taxonomy":"listing_amenity","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/amenities?post=34750"},{"taxonomy":"listing_facility","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/facilities?post=34750"},{"taxonomy":"listing_country","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listing_countries?post=34750"},{"taxonomy":"listing_state","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listing_states?post=34750"},{"taxonomy":"listing_city","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listing_cities?post=34750"},{"taxonomy":"listing_area","embeddable":true,"href":"https:\/\/www.yachttogo.com\/es\/wp-json\/wp\/v2\/listing_areas?post=34750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}