{"id":2009,"date":"2018-11-29T21:44:13","date_gmt":"2018-11-29T21:44:13","guid":{"rendered":"http:\/\/wordpress-89239-751689.cloudwaysapps.com\/?page_id=2009"},"modified":"2025-05-16T23:53:57","modified_gmt":"2025-05-16T20:53:57","slug":"boote-yachten-2","status":"publish","type":"page","link":"https:\/\/www.yachttogo.com\/de\/boats-yachts-2\/","title":{"rendered":"Boote und Yachten"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2009\" class=\"elementor elementor-2009\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6af3bcd e-flex e-con-boxed e-con e-parent\" data-id=\"6af3bcd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52e32de2 elementor-widget elementor-widget-text-editor\" data-id=\"52e32de2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 50px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\r\n\t\t<div id=\"listings_module_section\" data-in-vc-core=\"1\" class=\"listing-page listing-page-full-width module-wrap property-module-card\">\r\n\t\t\t<div data-in-vc-core=\"1\" class=\"listing-wrap which-layout-card  item-card-view\">\r\n\t\t\t\t<div id=\"module_listings\" class=\"row\">\r\n\t\t\t\t\t\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36909\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/chanel\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/05\/PRESTIGE-M48-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/05\/PRESTIGE-M48-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/05\/PRESTIGE-M48-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/05\/PRESTIGE-M48-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        18,000<sup>\u20ac<\/sup><sub>\/Woche<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/chanel\/\">CHANEL<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36909\" data-listing_id=\"36909\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36909\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"8352\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"MARZIATAGLIAMENTO\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36685\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/beyfendi-h-luxury-motor-yacht-charter-gocek\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Beyfendi-H-8-pax-Luxury-Motor-Yacht-Charter-Gocek.37-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"Motoryacht Beyfendi H vor Anker in den t\u00fcrkisfarbenen Gew\u00e4ssern von G\u00f6cek, T\u00fcrkei\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Beyfendi-H-8-pax-Luxury-Motor-Yacht-Charter-Gocek.37-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Beyfendi-H-8-pax-Luxury-Motor-Yacht-Charter-Gocek.37-16x12.jpeg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Beyfendi-H-8-pax-Luxury-Motor-Yacht-Charter-Gocek.37-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Beyfendi-H-8-pax-Luxury-Motor-Yacht-Charter-Gocek.37-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        3,000<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/beyfendi-h-luxury-motor-yacht-charter-gocek\/\">Beyfendi H: Falcon 86S Luxus-Motoryacht w\u00f6chentlicher Charter mit Crew G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36685\" data-listing_id=\"36685\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36685\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png\" class=\"img-responsive img-circle\" alt=\"YachttoGO Verifiziertes Symbol\" data-image-id=\"7502\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-481x500.png 481w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36637\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/mako-7-guest-luxury-motor-yacht-weekly-crewed-charter-gocek\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/MAKO-7-Guest-Luxury-Motor-Yacht-Crewed-Charter-Gocek-Bodrum-Marmaris.45.04-5-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"MAKO-Motoryacht in den t\u00fcrkisfarbenen Gew\u00e4ssern von G\u00f6cek in der T\u00fcrkei\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/MAKO-7-Guest-Luxury-Motor-Yacht-Crewed-Charter-Gocek-Bodrum-Marmaris.45.04-5-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/MAKO-7-Guest-Luxury-Motor-Yacht-Crewed-Charter-Gocek-Bodrum-Marmaris.45.04-5-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/MAKO-7-Guest-Luxury-Motor-Yacht-Crewed-Charter-Gocek-Bodrum-Marmaris.45.04-5-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,550<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/mako-7-guest-luxury-motor-yacht-weekly-crewed-charter-gocek\/\">MAKO: 7-G\u00e4ste-Luxus-Motoryacht Wochencharter mit Crew G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">7<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36637\" data-listing_id=\"36637\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36637\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png\" class=\"img-responsive img-circle\" alt=\"YachttoGO Verifiziertes Symbol\" data-image-id=\"8346\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-481x500.png 481w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36594\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/perfect-life-6-guest-classic-gulet-charter-gocek\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/perfect-life-3-cabin-gulet-gocek-yacht-charter23-1-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"Perfect Life 18-Meter-Gulet-Klassiker auf Kreuzfahrt in den ruhigen Buchten von G\u00f6cek, T\u00fcrkei\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/perfect-life-3-cabin-gulet-gocek-yacht-charter23-1-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/perfect-life-3-cabin-gulet-gocek-yacht-charter23-1-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/perfect-life-3-cabin-gulet-gocek-yacht-charter23-1-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        830<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/perfect-life-6-guest-classic-gulet-charter-gocek\/\">Perfect Life: 6-G\u00e4ste-Klassik-Gulet-Charter G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36594\" data-listing_id=\"36594\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36594\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8345\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/yigit-yerturk-gocek-yachtcharter-yachttogo.png 425w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36562\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/sacs-rebel-47\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/new1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/new1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/new1-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/new1-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,500<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/sacs-rebel-47\/\">Sacs Rebel 47<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36562\" data-listing_id=\"36562\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36562\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36116\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/at-marine-10-comfort\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.05-1-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.05-1-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.05-1-18x12.jpeg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.05-1-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.05-1-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        950<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/at-marine-10-comfort\/\">AT Marine 10 Komfort<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">0<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36116\" data-listing_id=\"36116\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36116\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36148\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/pirelli-42\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-450x300.png\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-450x300.png 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-300x200.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-1024x683.png 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-768x512.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-18x12.png 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-600x400.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-1140x760.png 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-120x80.png 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57-750x500.png 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_47_57.png 1536w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,000<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/pirelli-42\/\">Pirelli 42<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">14<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36148\" data-listing_id=\"36148\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36148\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36140\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/bwa-30\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-1024x683.jpg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-1536x1024.jpg 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-2048x1365.jpg 2048w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-600x400.jpg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/BWA-30_1-750x500.jpg 750w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,000<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/bwa-30\/\">BWA 30<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36140\" data-listing_id=\"36140\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36140\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36133\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/pirelli-35-4\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-450x300.png\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-450x300.png 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-300x200.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-1024x683.png 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-768x512.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-18x12.png 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-600x400.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-1140x760.png 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-120x80.png 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36-750x500.png 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-11_20_36.png 1536w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,200<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/pirelli-35-4\/\">Pirelli 35<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36133\" data-listing_id=\"36133\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36133\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36126\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/sacs\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/SACS-Strider-11-2-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/SACS-Strider-11-2-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/SACS-Strider-11-2-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/SACS-Strider-11-2-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/SACS-Strider-11-2-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,200<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/sacs\/\">SACS<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36126\" data-listing_id=\"36126\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36126\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36122\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/at-marine-10-sport\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.04-1-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.04-1-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-16-at-14.22.04-1-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        950<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/at-marine-10-sport\/\">AT Marine 10 Sport<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36122\" data-listing_id=\"36122\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36122\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36090\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/deniz-can-konyaalti-12-guest-motor-yacht-daily-rental-antalya\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/antalya-daily-yacht-tour-charter-04-07-22-44-55-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/antalya-daily-yacht-tour-charter-04-07-22-44-55-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/antalya-daily-yacht-tour-charter-04-07-22-44-55-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/antalya-daily-yacht-tour-charter-04-07-22-44-55-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        150<sup>\u20ac<\/sup><sub>\/saat<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/deniz-can-konyaalti-12-guest-motor-yacht-daily-rental-antalya\/\">Deniz Can: Konyaalt\u0131 12 G\u00e4ste Motoryacht Tagesmiete Antalya<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36090\" data-listing_id=\"36090\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36090\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8338\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/1000140150-360x360.png 360w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"36109\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/ranieri-renegade-22\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-450x300.png\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-450x300.png 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-300x200.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-1024x683.png 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-768x512.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-18x12.png 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-600x400.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-1140x760.png 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-120x80.png 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2-750x500.png 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-25-mar-2026-21_09_43-2.png 1536w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        350<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/ranieri-renegade-22\/\">Ranieri Renegade 22<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">0<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">0<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">10<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-36109\" data-listing_id=\"36109\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"36109\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"8171\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-768x768.png 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-600x600.png 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/ChatGPT-Image-10-apr-2026-11_00_48.png 1024w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34352\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/12-guest-motor-yacht-charter-sorrento\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/DJI_20250711135836_0003_D-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Brandneue Motoryacht 2025 Cayman 540 WA auf Kreuzfahrt an der Amalfik\u00fcste bei Sorrento\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/DJI_20250711135836_0003_D-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/DJI_20250711135836_0003_D-16x12.jpg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/DJI_20250711135836_0003_D-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/DJI_20250711135836_0003_D-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        3,200<sup>\u20ac<\/sup><sub>\/Prezzo giornaliero<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/12-guest-motor-yacht-charter-sorrento\/\">Cayman 540 WA: 12 G\u00e4ste Motoryacht Tagescharter Sorrento Italien<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                        \n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34352\" data-listing_id=\"34352\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34352\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"7289\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"NEVERGIVEUP\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34942\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/la-luna-82-pax-catamaran-bareboat-rental-gocek\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"La Luna Katamaran, Lagoon 450 Charter G\u00f6cek, Katamaran mieten Fethiye, Bareboat T\u00fcrkei, Luxusyachtcharter G\u00f6cek, 10 pax Katamaran T\u00fcrkei, YachttoGO\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10-300x199.jpeg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10-768x510.jpeg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10-18x12.jpeg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10-120x80.jpeg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Unknown-10.jpeg 1284w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        900<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/la-luna-82-pax-catamaran-bareboat-rental-gocek\/\">La Luna: 8+2 Pax Katamaran - Bareboat Vermietung G\u00f6cek, Fethiye<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4+1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34942\" data-listing_id=\"34942\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34942\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/ANCYRA-Sailing-Logo-2025_v2-scaled-1-150x150.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"7825\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/ANCYRA-Sailing-Logo-2025_v2-scaled-1-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/ANCYRA-Sailing-Logo-2025_v2-scaled-1-570x570.png 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/ANCYRA-Sailing-Logo-2025_v2-scaled-1-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/ANCYRA-Sailing-Logo-2025_v2-scaled-1-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/ANCYRA-Sailing-Logo-2025_v2-scaled-1-360x360.png 360w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34936\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/private-boat-charters-in-grand-cayman\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-1024x683.jpg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-1536x1024.jpg 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n-750x500.jpg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/618660635_17849933280625129_3515759097511033807_n.jpg 2048w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        250<sup>\u20ac<\/sup><sub>\/250<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/private-boat-charters-in-grand-cayman\/\">Island Vision Private Charters Limited - Private Bootscharter in Grand Cayman<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">10<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34936\" data-listing_id=\"34936\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34936\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-150x150.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"7820\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-500x500.png 500w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Island-Vision-Private-Charters-Logo.png 512w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34882\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/apreamare-54-12-guest-motor-yacht-daily-weekly-rental-amalfi-coast\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/2763786_e87d2182_5-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/2763786_e87d2182_5-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/2763786_e87d2182_5-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/2763786_e87d2182_5-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/2763786_e87d2182_5-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,300<sup>\u20ac<\/sup><sub>\/500,00<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/apreamare-54-12-guest-motor-yacht-daily-weekly-rental-amalfi-coast\/\">Apreamare 54: 12 G\u00e4ste Motoryacht Tages- und Wochenvermietung Amalfik\u00fcste Italien<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34882\" data-listing_id=\"34882\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34882\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Immagine-WhatsApp-2023-04-04-ore-18.23.38-150x150.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"7792\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Immagine-WhatsApp-2023-04-04-ore-18.23.38-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Immagine-WhatsApp-2023-04-04-ore-18.23.38-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Immagine-WhatsApp-2023-04-04-ore-18.23.38-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Immagine-WhatsApp-2023-04-04-ore-18.23.38-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Immagine-WhatsApp-2023-04-04-ore-18.23.38-360x360.jpg 360w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34750\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/prestige-400-10-pax-flybridge-motor-yacht-charter-split-croatia\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/y-20-1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Erleben Sie die Adria mit Stil. Buchen Sie die Prestige 400 f\u00fcr einen luxuri\u00f6sen Flybridge-Motoryachtcharter in Split. 2 Kabinen, Teakholzdecks und eine sonnendurchflutete Flybridge\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/y-20-1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/y-20-1-16x12.jpg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/y-20-1-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/y-20-1-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,000<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/prestige-400-10-pax-flybridge-motor-yacht-charter-split-croatia\/\">Prestige 400: 10 Pax Flybridge Motoryacht Charter Split, Kroatien<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">10<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34750\" data-listing_id=\"34750\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34750\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/logo-koristi-150x150.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"7723\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/logo-koristi-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/logo-koristi-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/logo-koristi-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/logo-koristi-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/logo-koristi-360x360.jpg 360w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34698\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/gulet-love-boat-36-pax-yacht-charter-bodrum-marmaris-turkey\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Luftaufnahme der Love Boat Gulet mit 36 G\u00e4sten beim Essen auf dem Achterdeck in Bodrum, T\u00fcrkei.\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-1024x683.jpg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3-750x500.jpg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/Love-Boat-36-Pax-Luxury-Gulet-Charter-Bodrum-Marmaris-3.jpg 1140w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        4,000<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/gulet-love-boat-36-pax-yacht-charter-bodrum-marmaris-turkey\/\">Gulet Love Boat: 36 Pax Yacht Charter Bodrum, Marmaris - T\u00fcrkei<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">16<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">18<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">36<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34698\" data-listing_id=\"34698\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34698\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34649\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/junior-irfan-gulet-8-guest-4-cabins-yacht-charter-bozburun\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/34Bozburun-Gulet-Charter-8-Guest-4-Cabins-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/34Bozburun-Gulet-Charter-8-Guest-4-Cabins-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/34Bozburun-Gulet-Charter-8-Guest-4-Cabins-16x12.jpeg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/34Bozburun-Gulet-Charter-8-Guest-4-Cabins-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/34Bozburun-Gulet-Charter-8-Guest-4-Cabins-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        880<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/junior-irfan-gulet-8-guest-4-cabins-yacht-charter-bozburun\/\">Junior \u0130rfan Gulet: 8 G\u00e4ste 4 Kabinen Yachtcharter Bozburun<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34649\" data-listing_id=\"34649\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34649\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"7648\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Umit Acun\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34534\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/luna-34-azimut-47-6-pax-motor-yacht-for-charter-gocek-marmaris\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/IMG_5558-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Luna 34 Azimut 47 Motoryacht auf Kreuzfahrt in Gocek; Luxus Flybridge und Interieur der Luna 34 Yacht; Private Yachtcharter Gocek Marmaris Sonnenuntergang.\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/IMG_5558-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/IMG_5558-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/IMG_5558-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,250<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/luna-34-azimut-47-6-pax-motor-yacht-for-charter-gocek-marmaris\/\">Luna 34: Azimut 47 6 Pax Motoryacht f\u00fcr Charter G\u00f6cek, Marmaris<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">3<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34534\" data-listing_id=\"34534\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34534\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-golden-verified-seal-logo-100x100-1.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"1\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-golden-verified-seal-logo-100x100-1.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-golden-verified-seal-logo-100x100-1-12x12.png 12w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34405\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/la-nonno-sunseeker-manhattan-66-charter-yate-de-lujo-en-mallorca\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-300x200.jpeg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-1024x683.jpeg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-768x512.jpeg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-1536x1024.jpeg 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-18x12.jpeg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-120x80.jpeg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1-750x500.jpeg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/02\/La-Nonno-Sunseeker_Exterior1.jpeg 1600w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        4,500<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/la-nonno-sunseeker-manhattan-66-charter-yate-de-lujo-en-mallorca\/\">La Nonno: Sunseeker Manhattan 66 - Luxus-Charter-Yacht auf Mallorca<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34405\" data-listing_id=\"34405\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34405\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"7455\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"KeystoneYachts\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34443\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/rent-passion-yacht-in-istanbul\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/IMG_5554-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/IMG_5554-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/IMG_5554-16x12.jpeg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/IMG_5554-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/IMG_5554-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        100<sup>\u20ac<\/sup><sub>\/Stunde<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/rent-passion-yacht-in-istanbul\/\">M\/Y PASSION: Privater Bosporus-Kreuzer &amp; Event-Yacht - Exklusiv-Charter in Istanbul<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">21<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34443\" data-listing_id=\"34443\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34443\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png\" class=\"img-responsive img-circle\" alt=\"YachttoGO Verifiziertes Symbol\" data-image-id=\"7502\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-481x500.png 481w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34426\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/m-y-brise-56-pax-power-catamaran\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/Luxury-Yacht-Brise-15-1-450x300.png\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/Luxury-Yacht-Brise-15-1-450x300.png 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/Luxury-Yacht-Brise-15-1-1140x760.png 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/01\/Luxury-Yacht-Brise-15-1-120x80.png 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        500<sup>\u20ac<\/sup><sub>\/Std.<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/m-y-brise-56-pax-power-catamaran\/\">M\/Y Brise: 56 Pax Power Katamaran Charter Bodrum, Istanbul<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">56<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34426\" data-listing_id=\"34426\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34426\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"7446\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"ArenYachting\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34255\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/canaima-12-guest-motor-yacht-daily-rental-ibiza\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"Die Canaima Salpa Avantgarde 35 kreuzt durch die t\u00fcrkisfarbenen Gew\u00e4sser von Ibiza und Formentera\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-300x200.jpeg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-1024x684.jpeg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-768x513.jpeg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-1536x1027.jpeg 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-18x12.jpeg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-120x80.jpeg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104-748x500.jpeg 748w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/DSC5104.jpeg 1616w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        0<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/canaima-12-guest-motor-yacht-daily-rental-ibiza\/\">Canaima: 12 G\u00e4ste Motoryacht Tagesvermietung Ibiza, Spanien<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">11<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34255\" data-listing_id=\"34255\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34255\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"6567\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"lamaribiza\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34215\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/carpediem-motor-yacht-charter-gocek\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/Unknown-4-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"6 Pax Motoryacht Charter Fethiye\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/Unknown-4-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/Unknown-4-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/11\/Unknown-4-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,000<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/carpediem-motor-yacht-charter-gocek\/\">Carpediem: 6 Pax Motoryacht Charter G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34215\" data-listing_id=\"34215\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34215\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"8185\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Alim Aytekin\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34163\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/neslisah-6-pax-gulet-charter-gocek\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Unknown-16-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"Nesli\u015fah Gulet 17.6m vor Anker in G\u00f6cek; Luxus-Gulet mit 3 Kabinen; Sonnendeck der Nesli\u015fah-Yacht mit Sonnenliegen.\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Unknown-16-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Unknown-16-1140x760.jpeg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Unknown-16-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        800<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/neslisah-6-pax-gulet-charter-gocek\/\">Nesli\u015fah: 6 Pax Gulet Charter G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34163\" data-listing_id=\"34163\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34163\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4845\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Turhan Alt\u0131ner\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34139\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/selenim\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Selenim-076-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Selenim-076-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Selenim-076-16x12.jpg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Selenim-076-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/08\/Selenim-076-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        750<sup>\u20ac<\/sup><sub>\/G\u00fcnl\u00fck (10.00-17.00)<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/selenim\/\">Selenim<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34139\" data-listing_id=\"34139\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34139\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4473\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Selen\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34088\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/enes-kaan\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM-600x400.jpeg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM-300x200.jpeg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM-768x512.jpeg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM-120x80.jpeg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM-750x500.jpeg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2022\/12\/WhatsApp-Image-2023-07-06-at-10.35.06-PM.jpeg 1024w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        600<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/enes-kaan\/\">Enes Kaan: 3 Kabinen 6 pax Gulet f\u00fcr Charter Fethiye, Gocek - T\u00fcrkei<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34088\" data-listing_id=\"34088\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34088\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4262\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Seher\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"34066\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/50-feet-catamaran-hourly-yacht-rental-in-dubai-13-pax-capacity\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-450x300.webp\" class=\"img-responsive wp-post-image\" alt=\"Stundenweise Yachtvermietung in Dubai\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-450x300.webp 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-300x199.webp 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-1024x681.webp 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-768x511.webp 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-1536x1021.webp 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-2048x1362.webp 2048w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-18x12.webp 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-1140x760.webp 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-120x80.webp 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/06\/Hourly-Yacht-for-Rent-in-Dubai-752x500.webp 752w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        400<sup>\u20ac<\/sup><sub>\/Stunde<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/50-feet-catamaran-hourly-yacht-rental-in-dubai-13-pax-capacity\/\">50-Fu\u00df-Katamaran: St\u00fcndliche Yachtvermietung in Dubai, Kapazit\u00e4t f\u00fcr 13 Passagiere<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">13<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-34066\" data-listing_id=\"34066\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"34066\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4215\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Fatimakhan\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33706\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/ayem-luxury-motor-yacht-charter-gocek-turkey\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/05\/yatch0-e1772374251807-450x300.png\" class=\"img-responsive wp-post-image\" alt=\"Ayem: Luxus-Motoryacht f\u00fcr Privatcharter. Eine schnittige, moderne Luxus-Motoryacht, die durch die t\u00fcrkisfarbenen Gew\u00e4sser der t\u00fcrkischen Riviera bei Fethiye gleitet.\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/05\/yatch0-e1772374251807-450x300.png 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/05\/yatch0-e1772374251807-18x12.png 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/05\/yatch0-e1772374251807-1140x760.png 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/05\/yatch0-e1772374251807-120x80.png 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,150<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/ayem-luxury-motor-yacht-charter-gocek-turkey\/\">AYEM: 10+2 G\u00e4ste Luxus Motoryacht Charter G\u00f6cek (All-Female Crew)<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">5<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">10<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33706\" data-listing_id=\"33706\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33706\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-100x100.jpeg\" class=\"img-responsive img-circle\" alt=\"Sibel \u015eim\u015fek - Ayem Luxus-Motoryacht-Charter G\u00f6cek - Eigner\" data-image-id=\"4154\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-100x100.jpeg 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-150x150.jpeg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-300x300.jpeg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-570x570.jpeg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-285x285.jpeg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-250x250.jpeg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/Unknown-360x360.jpeg 360w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33259\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/diamond-lila-gulet-luxury-yacht-for-charter-in-fethiye\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-750x500.jpg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-600x400.jpg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2-150x100.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DiamondLila01-2.jpg 1000w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,600<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/diamond-lila-gulet-luxury-yacht-for-charter-in-fethiye\/\">Diamant Lila Gulet: Luxus-Yacht f\u00fcr Charter in Fethiye<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">6<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">6<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33259\" data-listing_id=\"33259\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33259\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4139\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-735x760.jpg 735w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33255\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/jr-simay\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/1-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/1-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,650<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/jr-simay\/\">Junior Simay Trawler: Brandneue 2024 Yacht Charter f\u00fcr Fethiye &amp; G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33255\" data-listing_id=\"33255\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33255\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33230\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/gulet-segmen\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkei-Yacht-Segmen-5-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"T\u00fcrkei Gulet Yacht Segmen zu vermieten\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkei-Yacht-Segmen-5-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkei-Yacht-Segmen-5-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        7,700<sup>\u20ac<\/sup><sub>\/EUR pro Woche (Startpreis)<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/gulet-segmen\/\">Gulet Segmen: 16-Pax-Luxus-Yacht f\u00fcr Charter<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">7<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">7<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">14<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33230\" data-listing_id=\"33230\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33230\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4142\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Tumortour\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33228\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/blu-dream\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkey-Yacht-Charter-Blu-Dream-4-1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"T\u00fcrkei Yacht Charter, Blu Dream Gulet\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkey-Yacht-Charter-Blu-Dream-4-1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkey-Yacht-Charter-Blu-Dream-4-1-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        9,100<sup>\u20ac<\/sup><sub>\/EUR pro Woche (Startpreis)<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/blu-dream\/\">Blu Dream: Luxus-Gulet f\u00fcr Charter in Marmaris - 8 G\u00e4ste<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33228\" data-listing_id=\"33228\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33228\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4142\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Tumortour\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33226\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/vesta-1-sevil-gulet\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkey-Yacht-Charter-Vesta-1-Sevil-Yacht-6-1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"T\u00fcrkei Yachtcharter Gulet Vesta 1 Sevil Yacht\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkey-Yacht-Charter-Vesta-1-Sevil-Yacht-6-1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Turkey-Yacht-Charter-Vesta-1-Sevil-Yacht-6-1-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        14<sup>\u20ac<\/sup><sub>\/EUR pro Woche (Preis ab)<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/vesta-1-sevil-gulet\/\">Vesta 1 Sevil Gulet: 16 Pax Charter Yacht zu vermieten<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">8<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">8<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">15<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33226\" data-listing_id=\"33226\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33226\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4142\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Tumortour\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33224\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/princess-selin-gulet-yacht-charter-in-fethiye\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Prenses-Selin-Gulet-3-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Prenses Selin Gulet\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Prenses-Selin-Gulet-3-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/Prenses-Selin-Gulet-3-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,000<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/princess-selin-gulet-yacht-charter-in-fethiye\/\">Prinzessin Selin Gulet: Luxusyacht f\u00fcr Charter in Fethiye<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">8<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">8<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">16<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33224\" data-listing_id=\"33224\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33224\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4139\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-735x760.jpg 735w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33077\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/double-eagle-gulet-luxury-yacht-for-charter-in-bodrum\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/double-eagle-yacht-3-2-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/double-eagle-yacht-3-2-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/double-eagle-yacht-3-2-16x12.jpg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/double-eagle-yacht-3-2-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/double-eagle-yacht-3-2-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        4,000<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/double-eagle-gulet-luxury-yacht-for-charter-in-bodrum\/\">Doppeladler Gulet: Luxusyacht f\u00fcr Charter in Bodrum<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">5<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">5<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">10<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33077\" data-listing_id=\"33077\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33077\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4139\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-735x760.jpg 735w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"33075\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/by-cf-23m-luxury-trawler-4-cabins-sleeps-9\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"23 Meter langer Luxustrawler BY CF kreuzt entlang der t\u00fcrkischen Riviera\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-16x12.jpg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/bay-c-01-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,600<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/by-cf-23m-luxury-trawler-4-cabins-sleeps-9\/\">BY CF: 23m Luxus-Trawler - 4 Kabinen, 9 Schlafpl\u00e4tze<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">9<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-33075\" data-listing_id=\"33075\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"33075\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"3357\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/logo-yeni-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32949\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/aegean-clipper\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-750x500.jpg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-600x400.jpg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1-150x100.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/DSC_6687-1.jpg 1024w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        2,250<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/aegean-clipper\/\">Aegean Clipper: Luxus-Gulet f\u00fcr Charter in Bodrum<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">11<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">11<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">22<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32949\" data-listing_id=\"32949\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32949\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4139\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-735x760.jpg 735w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/5fe7d10b-b319-4da9-93c4-7ee424ac7e5a-2-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32933\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/sanka\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/IMG-20250310-WA0000-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/IMG-20250310-WA0000-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/IMG-20250310-WA0000-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/04\/IMG-20250310-WA0000-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        650<sup>\u20ac<\/sup><sub>\/Gece<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/sanka\/\">Sanka<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">7<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32933\" data-listing_id=\"32933\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32933\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"4058\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Kayakfahren\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32855\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/bogac-kaptan\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Gulet Charter G\u00f6cek - Gulet Vermietung G\u00f6cek\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-1024x683.jpg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-1536x1024.jpg 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-2048x1365.jpg 2048w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-750x500.jpg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-600x400.jpg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/DSC09980-min-150x100.jpg 150w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        700<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/bogac-kaptan\/\">Bo\u011fa\u00e7 Kaptan: Gulet Yacht Charter G\u00f6cek, Fethiye<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">4<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32855\" data-listing_id=\"32855\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32855\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4122\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-570x570.jpg 570w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2025\/03\/257DF2C4-D736-484C-9711-24624BF4BD9F-100x100.jpg 100w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32653\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                <span class=\"label-wrap top-left\">\n                    <span class=\"label label-featured\">Empfohlen<\/span>\n                <\/span>\n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/nomade-6-cabins-12-pax-lux-gulet-for-charter-in-fethiye-gocek\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/09\/6-cabins-12-Pax-Gulet-Yacht-For-Rent-2024-09-03-at-18.32.12-kopyasi-1-450x300.jpeg\" class=\"img-responsive wp-post-image\" alt=\"6 Kabinen 12 Pax Gulet Yacht zu vermieten Fethiye\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/09\/6-cabins-12-Pax-Gulet-Yacht-For-Rent-2024-09-03-at-18.32.12-kopyasi-1-450x300.jpeg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/09\/6-cabins-12-Pax-Gulet-Yacht-For-Rent-2024-09-03-at-18.32.12-kopyasi-1-16x12.jpeg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/09\/6-cabins-12-Pax-Gulet-Yacht-For-Rent-2024-09-03-at-18.32.12-kopyasi-1-120x80.jpeg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,100<sup>\u20ac<\/sup><sub>\/Nacht<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/nomade-6-cabins-12-pax-lux-gulet-for-charter-in-fethiye-gocek\/\">Nomade: 6 Kabinen, 12 Pax Lux Gulet f\u00fcr Charter in Fethiye, G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">6<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">6<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">12<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32653\" data-listing_id=\"32653\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32653\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-golden-verified-seal-logo-100x100-1.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"1\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-golden-verified-seal-logo-100x100-1.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-golden-verified-seal-logo-100x100-1-12x12.png 12w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32554\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/4-cabin-8-pax-gulet-yacht-charter-marmaris-turgut\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013869-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013869-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013869-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013869-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,016<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/4-cabin-8-pax-gulet-yacht-charter-marmaris-turgut\/\">INCI HANIM: 4 Kabinen 8 Pax Gulet Yacht Charter Marmaris Turgut<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32554\" data-listing_id=\"32554\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32554\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4064\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32538\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/aura-10-pax-hourly-yacht-charter-istanbul\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013800-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013800-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013800-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013800-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        84<sup>\u20ac<\/sup><sub>\/Stunde<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/aura-10-pax-hourly-yacht-charter-istanbul\/\">AURA: 10 Pax st\u00fcndlicher Yachtcharter Istanbul<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">0<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">1<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">10<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32538\" data-listing_id=\"32538\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32538\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4064\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32528\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/burkayim-3-cabin-6-pax-motor-yacht-charter-bozburun\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013693-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013693-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013693-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000013693-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        846<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/burkayim-3-cabin-6-pax-motor-yacht-charter-bozburun\/\">BURKAYIM: 3 Kabinen 6 Pax Motoryacht Charter Bozburun<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32528\" data-listing_id=\"32528\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32528\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4064\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32492\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/lycian-sirius-4-cabin-8-pax-gulet-yacht-charter-fethiye\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-600x400.jpg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-1024x682.jpg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-1536x1023.jpg 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-750x500.jpg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972-150x100.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012972.jpg 1600w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,000<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/lycian-sirius-4-cabin-8-pax-gulet-yacht-charter-fethiye\/\">LYC\u0130AN S\u0130R\u0130US: 4 Kabinen 8 Pax Gulet Yacht Charter Fethiye<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32492\" data-listing_id=\"32492\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32492\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" data-image-id=\"970\" id=\"profile-img-758\" src=\"https:\/\/www.yachttogo.com\/wp-content\/themes\/homey\/images\/avatar.png\" class=\"img-responsive img-circle\" alt=\"Ilhan Elibol\" width=\"36\" height=\"36\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32430\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/almila-5-cabin-10-pax-motor-yacht-charter-marmaris\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012861-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"Seitenansicht der Trawler-Motoryacht ALMILA, die in den K\u00fcstengew\u00e4ssern von Marmaris, T\u00fcrkei, unterwegs ist.\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012861-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012861-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000012861-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        3,600<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/almila-5-cabin-10-pax-motor-yacht-charter-marmaris\/\">ALMILA: W\u00f6chentliche Charter eines Trawlers\/einer Luxus-Motoryacht f\u00fcr 10 G\u00e4ste ab Marmaris, T\u00fcrkei<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">5<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">5<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">10<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32430\" data-listing_id=\"32430\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32430\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png\" class=\"img-responsive img-circle\" alt=\"YachttoGO Verifiziertes Symbol\" data-image-id=\"8349\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-481x500.png 481w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2026\/04\/YachttoGO-logo-magic-squere-500-x-500.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32418\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/zehra-sultan-8-cabin-16-pax-gulet-yacht-charter-marmaris\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000009757-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000009757-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000009757-16x12.jpg 16w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000009757-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/07\/1000009757-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        1,150<sup>\u20ac<\/sup><sub>\/Tag<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/zehra-sultan-8-cabin-16-pax-gulet-yacht-charter-marmaris\/\">ZEHRA SULTAN: 8 Kabinen 16 Pax Gulet Yacht Charter Marmaris<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">8<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">8<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">16<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32418\" data-listing_id=\"32418\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32418\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4064\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-96x96.png 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-300x300.png 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-100x100.png 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-150x150.png 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-12x12.png 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-285x285.png 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-250x250.png 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107-360x360.png 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/1000003107.png 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32322\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/dufour-470-denizderin\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-600x400.jpg 600w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-300x200.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-1024x683.jpg 1024w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-768x512.jpg 768w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-1536x1024.jpg 1536w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-18x12.jpg 18w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-120x80.jpg 120w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-750x500.jpg 750w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364-150x100.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/210316dy_1jml5364.jpg 2048w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        5,280<sup>\u20ac<\/sup><sub>\/\u0432 \u043d\u0435\u0434\u0435\u043b\u044e<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/dufour-470-denizderin\/\">Deniz Derin: Dufour 470 Segelyacht zu vermieten in G\u00f6cek<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">4<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">8<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32322\" data-listing_id=\"32322\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32322\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4069\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-100x100.jpg 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-12x12.jpg 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4.jpg 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\n<div class=\"item-wrap item-card-view infobox_trigger homey-matchHeight\"  data-dir=\"listing-card\"  data-id=\"32319\">\n    <div class=\"media property-item\">\n        \n            <div class=\"item-media item-media-thumb\">\n\n                \n                <a class=\"hover-effect\" href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/beneteau-oceanis-45-s-y-tayanita\/\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/oceanis45_0004formatok_0-450x300.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/oceanis45_0004formatok_0-450x300.jpg 450w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/oceanis45_0004formatok_0-1140x760.jpg 1140w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/oceanis45_0004formatok_0-120x80.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                <\/a>\n\n                <div class=\"title-head\">\n                                        <span class=\"item-price\">\n                        3,400<sup>\u20ac<\/sup><sub>\/\u0432 \u043d\u0435\u0434\u0435\u043b\u044e<\/sub>\n                    <\/span>\n                    \n                    <h2 class=\"title\"><a href=\"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/beneteau-oceanis-45-s-y-tayanita\/\">Tayanita: Beneteau Oceanis 45 \u2013 S\/Y<\/a><\/h2>\n\n                                        <ul class=\"item-amenities\">\n\n                                                <li>\n                            <i class=\"homey-icon homey-icon-hotel-double-bed\"><\/i>                            <span class=\"total-beds\">3<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-bathroom-shower-1\"><\/i>                            <span class=\"total-baths\">2<\/span>\n                        <\/li>\n                        \n                                                <li>\n                            <i class=\"homey-icon homey-icon-multiple-man-woman-2\"><\/i>                            <span class=\"total-guests\">6<\/span>\n                        <\/li>\n                                            <\/ul>\n                                    <\/div>\n                \n\n                                <div class=\"item-tools\">\n                    <div class=\"btn-group dropup\">\n                        <button class=\"btn-item-tools dropdown-toggle\" type=\"button\" data-toggle=\"dropdown\" aria-haspopup=\"true\" aria-expanded=\"false\">\n    <i class=\"homey-icon homey-icon-navigation-menu-vertical\" aria-hidden=\"true\"><\/i>\n<\/button>\n<ul class=\"dropdown-menu\">\n    <li>\n        <button type=\"button\" class=\"homey_compare compare-32319\" data-listing_id=\"32319\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Vergleichen        <\/button>\n    <\/li>\n    <li>\n        <button type=\"button\" class=\"add_fav\" data-listid=\"32319\" style=\"background: none; border: none; padding: 5px 20px; width: 100%; text-align: left; display: block; color: #333; font-size: 14px;\">\n            Zu den Favoriten hinzuf\u00fcgen        <\/button>\n    <\/li>\n<\/ul>                    <\/div>\n                <\/div>\n                \n                                <div class=\"item-user-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"36\" height=\"36\" src=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-96x96.jpg\" class=\"img-responsive img-circle\" alt=\"\" data-image-id=\"4069\" srcset=\"https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-96x96.jpg 96w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-300x300.jpg 300w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-100x100.jpg 100w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-150x150.jpg 150w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-12x12.jpg 12w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-285x285.jpg 285w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-250x250.jpg 250w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4-360x360.jpg 360w, https:\/\/www.yachttogo.com\/wp-content\/uploads\/2024\/06\/4.jpg 500w\" sizes=\"auto, (max-width: 36px) 100vw, 36px\" title=\"\">                <\/div>\n                            <\/div>\n    <\/div>\n<\/div><!-- .item-wrap -->\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t<div class=\"homey-loadmore loadmore text-center\">\r\n\t\t\t\t\t<a\r\n\t\t\t\t\tdata-query=\"\"\r\n\t\t\t\t\tdata-paged=\"2\"\r\n                    data-limit=\"51\"\r\n                    data-style=\"card\" \r\n                    data-booking_type=\"\" \r\n                    data-type=\"\" \r\n                    data-roomtype=\"\"\r\n                    data-country=\"\"  \r\n                    data-state=\"\" \r\n                    data-city=\"\" \r\n                    data-area=\"\" \r\n                    data-featured=\"\" \r\n                    data-offset=\"\"\r\n                    data-sortby=\"\"\r\n                    href=\"#\" \r\n\t\t\t\t\tclass=\"btn btn-primary btn-long\">\r\n\t\t\t\t\t\t<i id=\"spinner-icon\" class=\"homey-icon homey-icon-loading-half fa-pulse fa-spin fa-fw\" style=\"display: none;\"><\/i>\r\n\t\t\t\t\t\tMehr laden\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\r\n\t\t\t<\/div><!-- grid-listing-page -->\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"Tayanita: Cozy 2013 Beneteau Oceanis 45 for Charter in Turkey (Sleeps 8) Tayanita: The well-equipped 2013 Beneteau Oceanis 45, which is available for charter at Alesta Marina in Turkey, is a wonderful way to explore the Turkish coast. With three cabins and the added convenience of two heads (toilets) with showers, this roomy 13.94-meter sailing [...]","protected":false},"author":1,"featured_media":31148,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2009","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/pages\/2009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/comments?post=2009"}],"version-history":[{"count":8,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/pages\/2009\/revisions"}],"predecessor-version":[{"id":34009,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/pages\/2009\/revisions\/34009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/media\/31148"}],"wp:attachment":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/media?parent=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}