﻿{"id":5881,"date":"2022-01-25T13:36:31","date_gmt":"2022-01-25T10:36:31","guid":{"rendered":"https:\/\/www.yachttogo.com\/?post_type=listing&#038;p=5881"},"modified":"2026-01-28T15:33:06","modified_gmt":"2026-01-28T12:33:06","slug":"serenity-86-gulet-4-kabinen-8-passagiere-luxusyacht-zum-chartern-bodrum-marmaris-fethiye","status":"publish","type":"listing","link":"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/serenity-86-gulet-4-cabins-8-pax-luxury-yacht-for-charter-bodrum-marmaris-fethiye\/","title":{"rendered":"Serenity 86 Gulet- 4 Kabinen 8 Pax Luxusyacht f\u00fcr Charter - Bodrum, Marmaris, Fethiye"},"content":{"rendered":"<p>Serenity 86 Gulet ist eine 4-Kabinen-Yacht, die Platz f\u00fcr bis zu 8 G\u00e4ste f\u00fcr erstaunliche Yachtcharter rund um das \u00f6stliche Mittelmeer um, spezialisiert auf Bodrum, Marmaris, Fethiye.<\/p>\n<p>Serenity 86 Gulet wurde f\u00fcr alle Bed\u00fcrfnisse renoviert. Mit ihren gro\u00dfz\u00fcgigen R\u00e4umen und der hellen, modernen Inneneinrichtung bietet sie alles, was Sie f\u00fcr einen ruhigen und wundersch\u00f6nen Mieturlaub ben\u00f6tigen.<\/p>\n<p><strong>Treffen Sie unser Kabinenpersonal auf unserer w\u00f6chentlichen Tour und genie\u00dfen Sie das einzigartige Erlebnis, das wir Ihnen bieten!<\/strong><\/p>\n<p>Entspannen Sie sich auf Ihrer Charteryacht, die \u00fcber Entspannungsbereiche an Deck und Essbereiche im Freien verf\u00fcgt, und bewundern Sie Ihren faszinierenden Mittelmeert\u00f6rn. Sie k\u00f6nnen sich auf der Flybridge entspannen, den Wind genie\u00dfen, die Naturwunder und das t\u00fcrkisfarbene Wasser bewundern, verschiedene \u00d6kosysteme in verschiedenen Buchten sehen, sich auf dem Bug sonnen oder die Wasserspielzeuge auf dem Schiff nutzen. Es ist f\u00fcr jeden etwas dabei!<\/p>\n<ul>\n<li><strong>Essen und Trinken - <\/strong>Die Verpflegungspauschale betr\u00e4gt 380 \u20ac pro Woche\/pro Gast, die Getr\u00e4nkekosten richten sich nach Aufenthaltsdauer und Konsumation.<\/li>\n<li><strong>Reinigung \u2013 <\/strong>T\u00e4gliche Reinigung der Kabinen und B\u00e4der nach Wunsch und Bettw\u00e4sche sind im Preis inbegriffen und k\u00f6nnen t\u00e4glich gewechselt werden. Alle Badezimmer sind mit Haartrockner, Shampoo, Toilettenpapier, Seife, 3 Handt\u00fcchern und 3 gro\u00dfen Handt\u00fcchern pro Person und Woche ausgestattet.<\/li>\n<li><strong><strong>Wasserausr\u00fcstung und Spielzeug \u2013<\/strong><\/strong>Wasserski: Treibstoff pro Nutzung, Ringo-Ride: Treibstoff pro Nutzung, Wakeboard: Treibstoff pro Nutzung, 2 Kanus, 2 Paddelboards, Kneeboard, 8 Sonnenmatratzen, Sonnensegel f\u00fcr Schatten vor dem Gulet, Angelausr\u00fcstung (2x Ruten, 2x Langleinen, 6x Grundleinen), Masken, Schnorchel und Schwimmflossen<\/li>\n<li><strong>Hafen- und Fremdenverkehrsabgaben -<\/strong>\u00a0Hafengeb\u00fchren, private Yachth\u00e4fen und alle Zollgeb\u00fchren sind extra zu zahlen.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Serenity 86 Gulet is a 4 cabin yacht that can accommodate up to 8 guests for amazing yacht charters around the Eastern Mediterranean around, specializing in Bodrum, Marmaris, Fethiye. Serenity 86 Gulet was refurbished for all needs. With its large spaces and bright, modern interior decoration, it has everything you need for a peaceful and [&hellip;]<\/p>\n","protected":false},"author":7518,"featured_media":0,"parent":0,"menu_order":306,"template":"","listing_type":[78],"room_type":[166],"amenities":[12,20,23,36,126,128],"facilities":[134],"listing_countries":[37],"listing_states":[],"listing_cities":[],"listing_areas":[942],"class_list":["post-5881","listing","type-listing","status-publish","hentry","listing_type-gulet-charter","room_type-private-crewed-yacht-charter","listing_amenity-air-conditioning","listing_amenity-internet","listing_amenity-kitchen","listing_amenity-tv","listing_amenity-tv-cable","listing_amenity-wi-fi","listing_facility-water-toys","listing_country-yacht-charter-turkey","listing_area-marmaris-yacht-charter"],"_links":{"self":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listings\/5881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listings"}],"about":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/users\/7518"}],"version-history":[{"count":1,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listings\/5881\/revisions"}],"predecessor-version":[{"id":34459,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listings\/5881\/revisions\/34459"}],"wp:attachment":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/media?parent=5881"}],"wp:term":[{"taxonomy":"listing_type","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_type?post=5881"},{"taxonomy":"room_type","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/room_type?post=5881"},{"taxonomy":"listing_amenity","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/amenities?post=5881"},{"taxonomy":"listing_facility","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/facilities?post=5881"},{"taxonomy":"listing_country","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_countries?post=5881"},{"taxonomy":"listing_state","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_states?post=5881"},{"taxonomy":"listing_city","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_cities?post=5881"},{"taxonomy":"listing_area","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_areas?post=5881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}