{"id":10659,"date":"2022-07-28T17:49:47","date_gmt":"2022-07-28T14:49:47","guid":{"rendered":"https:\/\/www.yachttogo.com\/?post_type=listing&#038;p=10659"},"modified":"2022-07-28T17:51:18","modified_gmt":"2022-07-28T14:51:18","slug":"alfa-gulet-4-kabinen-8-passagiere-gulet-zum-chartern-gocek","status":"publish","type":"listing","link":"https:\/\/www.yachttogo.com\/de\/rental-boat-yacht\/alfa-gulet-4-cabin-8-pax-gulet-for-charter-gocek\/","title":{"rendered":"Alfa Gulet - 4 Kabinen 8 Pax Gulet f\u00fcr Charter - G\u00f6cek"},"content":{"rendered":"<p><span data-preserver-spaces=\"true\">Die Alfa Gulet ist eine Gulet mit 4 Kabinen, die bis zu 8 G\u00e4ste f\u00fcr unvergessliche Yachtcharter im \u00f6stlichen Mittelmeer und rund um Bodrum aufnehmen kann.<\/span><span data-preserver-spaces=\"true\">.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Die Alfa Gulet wurde komplett renoviert und bietet alles, was man f\u00fcr einen erholsamen und unvergesslichen Urlaub braucht. Mit ihren gro\u00dfz\u00fcgigen R\u00e4umlichkeiten und der hellen, modernen Innenausstattung bietet sie alles, was man sich f\u00fcr einen ruhigen und sch\u00f6nen Urlaub w\u00fcnscht.<\/span><\/p>\n<p><strong><span data-preserver-spaces=\"true\">Lernen Sie unser Kabinenpersonal kennen und genie\u00dfen Sie das einzigartige Erlebnis, das wir Ihnen bieten!<\/span><\/strong><\/p>\n<p><span data-preserver-spaces=\"true\">Sie k\u00f6nnen sich in Ihrem Luxus entspannen\u00a0<\/span><span data-preserver-spaces=\"true\">Charter-Yacht<\/span><span data-preserver-spaces=\"true\">\u00a0mit seinen Einrichtungen wie den Entspannungsbereichen an Deck und den Essbereichen im Freien und bewundern Sie Ihre faszinierende Mittelmeer-Kreuzfahrt. Ob Sie sich auf der Flybridge entspannen, den Wind genie\u00dfen, die Naturwunder und das t\u00fcrkisfarbene Wasser beobachten, verschiedene \u00d6kosysteme in verschiedenen Buchten kennenlernen, sich am Bug sonnen oder das Wasserspielzeug auf dem Schiff nutzen m\u00f6chten, es ist f\u00fcr jeden etwas dabei!<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Alfa Gulet is a 4 cabin gulet that can accommodate up to 8 guests for amazing yacht charters around the Eastern Mediterranean around, specializing in Bodrum. Alfa Gulet was refurbished for all needs. With its large spaces and bright, modern interior decoration, it has everything you need for a peaceful and wonderful rental holiday. Meet [&hellip;]<\/p>\n","protected":false},"author":453,"featured_media":10686,"parent":0,"menu_order":158,"template":"","listing_type":[78],"room_type":[166],"amenities":[],"facilities":[],"listing_countries":[37],"listing_states":[],"listing_cities":[],"listing_areas":[],"class_list":["post-10659","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_type-gulet-charter","room_type-private-crewed-yacht-charter","listing_country-yacht-charter-turkey"],"_links":{"self":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listings\/10659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listings"}],"about":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/users\/453"}],"version-history":[{"count":0,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listings\/10659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/media\/10686"}],"wp:attachment":[{"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/media?parent=10659"}],"wp:term":[{"taxonomy":"listing_type","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_type?post=10659"},{"taxonomy":"room_type","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/room_type?post=10659"},{"taxonomy":"listing_amenity","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/amenities?post=10659"},{"taxonomy":"listing_facility","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/facilities?post=10659"},{"taxonomy":"listing_country","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_countries?post=10659"},{"taxonomy":"listing_state","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_states?post=10659"},{"taxonomy":"listing_city","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_cities?post=10659"},{"taxonomy":"listing_area","embeddable":true,"href":"https:\/\/www.yachttogo.com\/de\/wp-json\/wp\/v2\/listing_areas?post=10659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}